{"id":30815,"date":"2025-02-14T01:04:53","date_gmt":"2025-02-14T07:04:53","guid":{"rendered":"https:\/\/enertik.com\/mx\/?post_type=product&#038;p=30815"},"modified":"2026-08-30T19:25:35","modified_gmt":"2026-08-31T01:25:35","slug":"victron-cargador-dc-dc-orion-tr-smart-aislado-24-24-12a-280w","status":"publish","type":"product","link":"https:\/\/enertik.com\/mx\/tienda\/cargadores-de-baterias\/victron-cargador-dc-dc-orion-tr-smart-aislado-2424-12a-280w\/","title":{"rendered":"Victron \u2013 Cargador DC-DC Orion-Tr Smart Aislado 24\/24-12A (280W)"},"content":{"rendered":"\t\t<div data-elementor-type=\"product-post\" data-elementor-id=\"30815\" class=\"elementor elementor-30815\" data-elementor-post-type=\"product\">\n\t\t\t\t\t\t<section class=\"wd-negative-gap elementor-section elementor-top-section elementor-element elementor-element-1bcf026 Product_Description elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1bcf026\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8bab74d\" data-id=\"8bab74d\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"wd-negative-gap elementor-section elementor-inner-section elementor-element elementor-element-27e63d6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"27e63d6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-2e06830\" data-id=\"2e06830\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d4df91b elementor-widget elementor-widget-wd_tabs\" data-id=\"d4df91b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"wd-tabs tabs-design-default\">\n\t\t\t<div class=\"wd-tabs-header text-center\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"wd-nav-wrapper wd-nav-tabs-wrapper wd-mb-action-swipe color-scheme-light\">\n\t\t\t\t\t<ul class=\"wd-nav wd-nav-tabs wd-icon-pos-left wd-style-underline\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t<a href=\"#\" class=\"wd-nav-link\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<span class=\"nav-link-text wd-tabs-title\">\n\t\t\t\t\t\t\t\t\t\tDESCRIPCI\u00d3N\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/li>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t<a href=\"#\" class=\"wd-nav-link\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<span class=\"nav-link-text wd-tabs-title\">\n\t\t\t\t\t\t\t\t\t\tESPECIFICACIONES\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/li>\n\n\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t<div class=\"wd-tabs-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"wd-tab-content wd-entry-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div >\n\t\t\t\t\t\t\t\t<h2>VENTAJAS<\/h2><ul class=\"ulMiddle\"><li>M\u00f3dulo de Bluetooth integrado<\/li><li>Configuraci\u00f3n de par\u00e1metros y monitoreo desde APP m\u00f3vil<\/li><li>Algoritmo de carga de bater\u00edas (configurable) o salida fija.<\/li><li>Compatibilidad inteligente con el alternador: mecanismo de detecci\u00f3n de motor en marcha.<\/li><li>Algoritmo de carga inteligente adaptable de 3 etapas garantiza la carga completa de las bater\u00edas mientras alarga su vida \u00fatil<\/li><li>Adecuado para su uso en veh\u00edculos con un alternador inteligente (motores Euro 5 y Euro 6): detecci\u00f3n integrada de apagado del motor<\/li><li>On\/Off remoto<\/li><li>Funcionamiento en paralelo sin limitaci\u00f3n de n\u00famero de unidades<\/li><li>Protecci\u00f3n contra cortocircuito, sobrecargas y sobretemperatura<\/li><li>Protecci\u00f3n IP43 (Si se instala con los bornes de tornillo orientados hacia abajo.)<\/li><li>Bornes de tornillo, no se necesitan herramientas especiales para su instalaci\u00f3n<\/li><\/ul><p>\u00a0<\/p><h2>PROTECCIONES DEL EQUIPO<\/h2><ul class=\"ulMiddle\"><li class=\"ulBgColor\">Protecci\u00f3n contra la entrada de polvo y agua IP43 (Si se instala con los bornes de tornillo orientados hacia abajo.)<\/li><li class=\"ulBgColor\">Sobrecalentamiento<\/li><li>Cortocircuito<\/li><li>Sobrecargas<\/li><li>Fusibles integrados<\/li><\/ul>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"wd-tab-content wd-entry-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div >\n\t\t\t\t\t\t\t\t<table><tbody><tr class=\"tbBorderNone\"><td class=\"tbLeft\">Modelo<\/td><td>VICTRON ORI242428120<\/td><\/tr><tr><td class=\"tbTit\" colspan=\"2\">Entrada<\/td><\/tr><tr><td class=\"tbLeft\">Rango de tensi\u00f3n de entrada<\/td><td>16-35 VCC<\/td><\/tr><tr><td class=\"tbLeft\">Desconexi\u00f3n por tensi\u00f3n baja<\/td><td>14V<\/td><\/tr><tr class=\"tbBorderNone\"><td class=\"tbLeft\">Reconexi\u00f3n<\/td><td>15V<\/td><\/tr><tr><td class=\"tbTit\" colspan=\"2\">Salida<\/td><\/tr><tr><td class=\"tbLeft\">Tensi\u00f3n de salida nominal<\/td><td>24.2V<\/td><\/tr><tr><td class=\"tbLeft\">Rango ajustable para la tensi\u00f3n de salida<\/td><td>20-30 V<\/td><\/tr><tr><td class=\"tbLeft\">Tolerancia de la tensi\u00f3n de salida<\/td><td>+\/- 0,2 V<\/td><\/tr><tr><td class=\"tbLeft\">Nivel de ruido<\/td><td>2 mV rms<\/td><\/tr><tr><td class=\"tbLeft\">Corriente de salida cont. a tensi\u00f3n nominal de salida y 40oC<\/td><td>12A<\/td><\/tr><tr><td class=\"tbLeft\">Corriente de salida m\u00e1xima (10 s) a tensi\u00f3n nominal de salida menos 20 %<\/td><td>15A<\/td><\/tr><tr><td class=\"tbLeft\">Corriente de cortocircuito<\/td><td>30A<\/td><\/tr><tr><td class=\"tbLeft\">Potencia cont. de salida a 25 \u00b0C<\/td><td>320W<\/td><\/tr><tr><td class=\"tbLeft\">Potencia cont. de salida a 40 \u00b0C<\/td><td>280W<\/td><\/tr><tr><td class=\"tbLeft\">Eficiencia<\/td><td>89%<\/td><\/tr><tr class=\"tbBorderNone\"><td class=\"tbLeft\">Corriente de carga de entrada sin carga<\/td><td>&lt; 80 mA<\/td><\/tr><tr><td class=\"tbTit\" colspan=\"2\">Caracter\u00edsticas del equipo<\/td><\/tr><tr><td class=\"tbLeft\">Autoconsumo<\/td><td>&lt; 1 mA<\/td><\/tr><tr><td class=\"tbLeft\">Aislamiento galv\u00e1nico<\/td><td>200 V entre entrada, salida y carcasa<\/td><\/tr><tr><td class=\"tbLeft\">Conexi\u00f3n CC<\/td><td>Bornes de tornillo<\/td><\/tr><tr class=\"tbBorderNone\"><td class=\"tbLeft\">Secci\u00f3n de cable m\u00e1xima:<\/td><td>16 mm2 (AWG6)<\/td><\/tr><tr><td class=\"tbTit\" colspan=\"2\">Ambiente<\/td><\/tr><tr><td class=\"tbLeft\">Rango de temperatura de trabajo<\/td><td>-20 a +55\u00b0C (reducci\u00f3n de potencia del 3 % por cada \u00b0C sobre 40\u00b0C)<\/td><\/tr><tr><td class=\"tbLeft\">Humedad<\/td><td>M\u00e1x. 95 % sin condensaci\u00f3n<\/td><\/tr><tr class=\"tbBorderNone\"><td class=\"tbLeft\">Grado de protecci\u00f3n IP<\/td><td>IP43 (componentes electr\u00f3nicos), IP22 (\u00e1rea de conexi\u00f3n)<\/td><\/tr><tr><td class=\"tbTit\" colspan=\"2\">Caracter\u00edsticas f\u00edsicas<\/td><\/tr><tr><td class=\"tbLeft\">Peso<\/td><td>1.3kg<\/td><\/tr><tr class=\"tbBorderNone\"><td class=\"tbLeft\">Dimensiones (al x an x p, en mm)<\/td><td>130 x 186 x 70<\/td><\/tr><tr><td class=\"tbTit\" colspan=\"2\">Normativas<\/td><\/tr><tr><td class=\"tbLeft\">Seguridad<\/td><td>EN 60950<\/td><\/tr><tr><td class=\"tbLeft\">Emisiones\/Normativas<\/td><td>EN 61000-6-3, EN 55014-1 \/ EN 61000-6-2, EN 61000-6-1, EN 55014-2<\/td><\/tr><tr><td class=\"tbLeft\">Directiva de automoci\u00f3n<\/td><td>ECE R10-5<\/td><\/tr><\/tbody><\/table>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"wd-negative-gap elementor-section elementor-top-section elementor-element elementor-element-caf8062 Product_Description elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"caf8062\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e0b8771\" data-id=\"e0b8771\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-34f7483 elementor-widget elementor-widget-wd_text_block\" data-id=\"34f7483\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_text_block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"wd-text-block reset-last-child text-left\">\n\t\t\t\n\t\t\t<h2><span style=\"color: var(--wd-title-color); font-family: var(--wd-title-font); font-size: 22px; font-style: var(--wd-title-font-style); font-weight: var(--wd-title-font-weight); text-transform: var(--wd-title-transform);\">VictronConnect<\/span><\/h2><p>VictronConnect le permite obtener informaci\u00f3n de estado en tiempo real y configurar cualquier producto de Victron que tenga Bluetooth integrado o que est\u00e9 conectado a una mochila VE.Direct Bluetooth Smart.<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"wd-negative-gap elementor-section elementor-top-section elementor-element elementor-element-d71b127 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d71b127\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-3a8b726\" data-id=\"3a8b726\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3e2905a elementor-widget elementor-widget-image\" data-id=\"3e2905a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/play.google.com\/store\/apps\/details?id=com.victronenergy.victronconnect\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img decoding=\"async\" class=\" wd-lazy-fade\" src=\"https:\/\/enertik.com\/mx\/wp-content\/themes\/woodmart\/images\/lazy.svg\" data-src=\"https:\/\/enertik.com\/mx\/wp-content\/uploads\/sites\/4\/elementor\/thumbs\/google-play@2x-qbzbk8ticrz13c77bky1ax3fdikjwztfodl0uht9ts.png\" title=\"google play@2x\" alt=\"google play@2x\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-ab6cb55\" data-id=\"ab6cb55\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3a09635 elementor-widget elementor-widget-image\" data-id=\"3a09635\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/apps.apple.com\/us\/app\/victron-connect\/id943840744\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img decoding=\"async\" class=\" wd-lazy-fade\" src=\"https:\/\/enertik.com\/mx\/wp-content\/themes\/woodmart\/images\/lazy.svg\" data-src=\"https:\/\/enertik.com\/mx\/wp-content\/uploads\/sites\/4\/elementor\/thumbs\/ios-appstore@2x-qbzbk8ticrz13c77bky1ax3fdikjwztfodl0uht9ts.png\" title=\"ios appstore@2x\" alt=\"ios appstore@2x\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-a140446 elementor-hidden-mobile\" data-id=\"a140446\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3b068d4 elementor-widget elementor-widget-image\" data-id=\"3b068d4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/apps.apple.com\/us\/app\/victron-connect\/id943840744\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img decoding=\"async\" class=\" wd-lazy-fade\" src=\"https:\/\/enertik.com\/mx\/wp-content\/themes\/woodmart\/images\/lazy.svg\" data-src=\"https:\/\/enertik.com\/mx\/wp-content\/uploads\/sites\/4\/elementor\/thumbs\/mac-app-store-badge-qbzbk8ticryz1ogrvz2sg7ifc4q4sembf118n75s00.png\" title=\"Mac App Store Badge\" alt=\"Mac App Store Badge\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-75ca6bd elementor-hidden-mobile\" data-id=\"75ca6bd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-838b7d9 elementor-widget elementor-widget-image\" data-id=\"838b7d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/apps.apple.com\/us\/app\/victron-connect\/id943840744\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img decoding=\"async\" class=\" wd-lazy-fade\" src=\"https:\/\/enertik.com\/mx\/wp-content\/themes\/woodmart\/images\/lazy.svg\" data-src=\"https:\/\/enertik.com\/mx\/wp-content\/uploads\/sites\/4\/elementor\/thumbs\/download-for-windows-badge2-qbzbk8ticryvz6v4qk9x654xa1yi3itn107kc96j9c.png\" title=\"Download For Windows Badge2\" alt=\"Download For Windows Badge2\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"wd-negative-gap elementor-section elementor-top-section elementor-element elementor-element-f90d78a Link_Buttons elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f90d78a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-custom\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-3139e65\" data-id=\"3139e65\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3d15c1e elementor-view-framed elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"3d15c1e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/enertik.com\/wp-content\/uploads\/sites\/2\/documentos\/folletos\/datasheet-orion-tr-smart-dc-dc-chargers-isolated-250-400w-es.pdf\" target=\"_blank\" class=\"elementor-icon\" tabindex=\"-1\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-book-open\" viewBox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M542.22 32.05c-54.8 3.11-163.72 14.43-230.96 55.59-4.64 2.84-7.27 7.89-7.27 13.17v363.87c0 11.55 12.63 18.85 23.28 13.49 69.18-34.82 169.23-44.32 218.7-46.92 16.89-.89 30.02-14.43 30.02-30.66V62.75c.01-17.71-15.35-31.74-33.77-30.7zM264.73 87.64C197.5 46.48 88.58 35.17 33.78 32.05 15.36 31.01 0 45.04 0 62.75V400.6c0 16.24 13.13 29.78 30.02 30.66 49.49 2.6 149.59 12.11 218.77 46.95 10.62 5.35 23.21-1.94 23.21-13.46V100.63c0-5.29-2.62-10.14-7.27-12.99z\"><\/path><\/svg>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tFOLLETO\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-33ba387\" data-id=\"33ba387\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4db2e88 elementor-view-framed elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"4db2e88\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/enertik.com\/wp-content\/uploads\/sites\/2\/documentos\/manuales\/34439-orion-tr_smart_dc-dc_charger-pdf-es.pdf\" target=\"_blank\" class=\"elementor-icon\" tabindex=\"-1\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-book\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M448 360V24c0-13.3-10.7-24-24-24H96C43 0 0 43 0 96v320c0 53 43 96 96 96h328c13.3 0 24-10.7 24-24v-16c0-7.5-3.5-14.3-8.9-18.7-4.2-15.4-4.2-59.3 0-74.7 5.4-4.3 8.9-11.1 8.9-18.6zM128 134c0-3.3 2.7-6 6-6h212c3.3 0 6 2.7 6 6v20c0 3.3-2.7 6-6 6H134c-3.3 0-6-2.7-6-6v-20zm0 64c0-3.3 2.7-6 6-6h212c3.3 0 6 2.7 6 6v20c0 3.3-2.7 6-6 6H134c-3.3 0-6-2.7-6-6v-20zm253.4 250H96c-17.7 0-32-14.3-32-32 0-17.6 14.4-32 32-32h285.4c-1.9 17.1-1.9 46.9 0 64z\"><\/path><\/svg>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tMANUAL\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-0d6446e\" data-id=\"0d6446e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-95203ba elementor-view-framed elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"95203ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/enertik.com\/wp-content\/uploads\/sites\/2\/documentos\/manuales\/8778-victronconnect_manual-pdf-es.pdf\" target=\"_blank\" class=\"elementor-icon\" tabindex=\"-1\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-book\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M448 360V24c0-13.3-10.7-24-24-24H96C43 0 0 43 0 96v320c0 53 43 96 96 96h328c13.3 0 24-10.7 24-24v-16c0-7.5-3.5-14.3-8.9-18.7-4.2-15.4-4.2-59.3 0-74.7 5.4-4.3 8.9-11.1 8.9-18.6zM128 134c0-3.3 2.7-6 6-6h212c3.3 0 6 2.7 6 6v20c0 3.3-2.7 6-6 6H134c-3.3 0-6-2.7-6-6v-20zm0 64c0-3.3 2.7-6 6-6h212c3.3 0 6 2.7 6 6v20c0 3.3-2.7 6-6 6H134c-3.3 0-6-2.7-6-6v-20zm253.4 250H96c-17.7 0-32-14.3-32-32 0-17.6 14.4-32 32-32h285.4c-1.9 17.1-1.9 46.9 0 64z\"><\/path><\/svg>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tVICTRONCONNECT\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-9eb8f80\" data-id=\"9eb8f80\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-64d136d elementor-view-framed elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"64d136d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/enertik.com\/wp-content\/uploads\/sites\/2\/documentos\/manuales\/engine-on-detection-set-up-orion-tr-smart-dc-dc-charger-es.pdf\" target=\"_blank\" class=\"elementor-icon\" tabindex=\"-1\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-book-reader\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M352 96c0-53.02-42.98-96-96-96s-96 42.98-96 96 42.98 96 96 96 96-42.98 96-96zM233.59 241.1c-59.33-36.32-155.43-46.3-203.79-49.05C13.55 191.13 0 203.51 0 219.14v222.8c0 14.33 11.59 26.28 26.49 27.05 43.66 2.29 131.99 10.68 193.04 41.43 9.37 4.72 20.48-1.71 20.48-11.87V252.56c-.01-4.67-2.32-8.95-6.42-11.46zm248.61-49.05c-48.35 2.74-144.46 12.73-203.78 49.05-4.1 2.51-6.41 6.96-6.41 11.63v245.79c0 10.19 11.14 16.63 20.54 11.9 61.04-30.72 149.32-39.11 192.97-41.4 14.9-.78 26.49-12.73 26.49-27.06V219.14c-.01-15.63-13.56-28.01-29.81-27.09z\"><\/path><\/svg>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tGU\u00cdA - DETECCI\u00d3N DEL MOTOR\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"wd-negative-gap elementor-section elementor-top-section elementor-element elementor-element-c0f4e5d mas_recursos elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c0f4e5d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fed34e1\" data-id=\"fed34e1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4efb0ae elementor-widget elementor-widget-wd_text_block\" data-id=\"4efb0ae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_text_block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"wd-text-block reset-last-child text-left\">\n\t\t\t\n\t\t\t<h2>\u00a0M\u00c1S INFORMACI\u00d3N\u00a0<\/h2>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0e60e17 elementor-button-success elementor-align-left elementor-mobile-align-left elementor-widget elementor-widget-button\" data-id=\"0e60e17\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xs elementor-animation-grow\" href=\"https:\/\/enertik.com\/wp-content\/uploads\/sites\/2\/documentos\/certificados\/iso9001-certificate-2021-en.pdf\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-file-alt\" viewBox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224 136V0H24C10.7 0 0 10.7 0 24v464c0 13.3 10.7 24 24 24h336c13.3 0 24-10.7 24-24V160H248c-13.2 0-24-10.8-24-24zm64 236c0 6.6-5.4 12-12 12H108c-6.6 0-12-5.4-12-12v-8c0-6.6 5.4-12 12-12h168c6.6 0 12 5.4 12 12v8zm0-64c0 6.6-5.4 12-12 12H108c-6.6 0-12-5.4-12-12v-8c0-6.6 5.4-12 12-12h168c6.6 0 12 5.4 12 12v8zm0-72v8c0 6.6-5.4 12-12 12H108c-6.6 0-12-5.4-12-12v-8c0-6.6 5.4-12 12-12h168c6.6 0 12 5.4 12 12zm96-114.1v6.1H256V0h6.1c6.4 0 12.5 2.5 17 7l97.9 98c4.5 4.5 7 10.6 7 16.9z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Certificado ISO9001<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-15c7a0a elementor-button-success elementor-align-left elementor-mobile-align-left elementor-widget elementor-widget-button\" data-id=\"15c7a0a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xs elementor-animation-grow\" href=\"https:\/\/enertik.com\/wp-content\/uploads\/sites\/2\/documentos\/certificados\/certificate-automotive-ece-r10-6-4722-orion-tr-smart-isolated-dc-dc-converter-charger-360w-400w.pdf\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-file-alt\" viewBox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224 136V0H24C10.7 0 0 10.7 0 24v464c0 13.3 10.7 24 24 24h336c13.3 0 24-10.7 24-24V160H248c-13.2 0-24-10.8-24-24zm64 236c0 6.6-5.4 12-12 12H108c-6.6 0-12-5.4-12-12v-8c0-6.6 5.4-12 12-12h168c6.6 0 12 5.4 12 12v8zm0-64c0 6.6-5.4 12-12 12H108c-6.6 0-12-5.4-12-12v-8c0-6.6 5.4-12 12-12h168c6.6 0 12 5.4 12 12v8zm0-72v8c0 6.6-5.4 12-12 12H108c-6.6 0-12-5.4-12-12v-8c0-6.6 5.4-12 12-12h168c6.6 0 12 5.4 12 12zm96-114.1v6.1H256V0h6.1c6.4 0 12.5 2.5 17 7l97.9 98c4.5 4.5 7 10.6 7 16.9z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Certificado ECE R10\/6<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7043aed elementor-button-success elementor-align-left elementor-mobile-align-left elementor-widget elementor-widget-button\" data-id=\"7043aed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xs elementor-animation-grow\" href=\"https:\/\/enertik.com\/wp-content\/uploads\/sites\/2\/documentos\/certificados\/orion-tr-smart-2021-12-29.pdf\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-file-alt\" viewBox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224 136V0H24C10.7 0 0 10.7 0 24v464c0 13.3 10.7 24 24 24h336c13.3 0 24-10.7 24-24V160H248c-13.2 0-24-10.8-24-24zm64 236c0 6.6-5.4 12-12 12H108c-6.6 0-12-5.4-12-12v-8c0-6.6 5.4-12 12-12h168c6.6 0 12 5.4 12 12v8zm0-64c0 6.6-5.4 12-12 12H108c-6.6 0-12-5.4-12-12v-8c0-6.6 5.4-12 12-12h168c6.6 0 12 5.4 12 12v8zm0-72v8c0 6.6-5.4 12-12 12H108c-6.6 0-12-5.4-12-12v-8c0-6.6 5.4-12 12-12h168c6.6 0 12 5.4 12 12zm96-114.1v6.1H256V0h6.1c6.4 0 12.5 2.5 17 7l97.9 98c4.5 4.5 7 10.6 7 16.9z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Declaraci\u00f3n de Conformidad CE<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Modelo: 24V \u2013&gt; 24V 12A\u00a0 (280W)<\/p>\n<p>El cargador Orion-Tr Smart Aislado es un cargador profesional de CC a CC, adaptable de 3 etapas y con Bluetooth integrado.<\/p>\n<p>Es muy \u00fatil en sistemas de bater\u00eda en veh\u00edculos o embarcaciones en los que el alternador (inteligente) y la bater\u00eda de arranque se utilizan para cargar la bater\u00eda de servicio. La unidad puede monitorizarse y programarse v\u00eda Bluetooth y se puede controlar a distancia a trav\u00e9s de un interruptor remoto de encendido\/apagado, y dispone de un mecanismo de detecci\u00f3n de motor en marcha.<\/p>\n<div class=\"page\" title=\"Page 1\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>El cargador CC-CC Orion-Tr Smart Aislado puede actuar como un cargador de bateri\u0301as CC-CC o como fuente de alimentacio\u0301n (tambie\u0301n esta\u0301 disen\u0303ado para su uso como fuente de tensio\u0301n constante).<\/p>\n<p>Gracias a su dise\u00f1o especial, puede funcionar bien en el caso de veh\u00edculos con un alternador inteligente Euro 5 o Euro 6, que a menudo proporcionan una tensio\u0301n de carga demasiado baja incluso cuando el motor esta\u0301 funcionando, o en el caso de sistemas con cables muy largos, como sucede a menudo en barcos y caravanas, producie\u0301ndose cai\u0301das de tensio\u0301n. En tales circunstancias, una carga precisa y controlada es imprescindible para cargar por completo la bateri\u0301a auxiliar, protegiendo al mismo tiempo la bateri\u0301a de arranque de la descarga, y Orion-Tr Smart Aislado es capaz de manejar todo el proceso de forma perfecta.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>La familia de Orion-Tr Smart tiene modelos diversos para usarse en sistemas de 12V, 24V o 48V, ofreciendo un amplio rango de tensio\u0301n de entrada y salida para cada necesidad.\u00a0 Son adecuados tanto para bater\u00edas de plomo-\u00e1cido como de litio. Se puede conectar un n\u00famero ilimitado de unidades en paralelo para incrementar la potencia de salida.<\/p>\n<p>Dise\u00f1ado para funcionar en altas temperaturas de hasta 55\u00baC, con toda la potencia nominal de salida hasta los 40\u00baC.<\/p>\n","protected":false},"featured_media":30818,"comment_status":"open","ping_status":"closed","template":"","meta":{"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","inline_featured_image":false,"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":""},"product_brand":[5296],"product_cat":[1740],"product_tag":[],"class_list":["post-30815","product","type-product","status-publish","has-post-thumbnail","product_brand-victron-energy","product_cat-cargadores-de-baterias","pa_corriente-12a","pa_gtin-4635","pa_serie-serie-orion-tr-smart-aislado","pa_voltaje-24v","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"bundled_by":[],"bundle_stock_status":"instock","bundle_stock_quantity":5,"bundle_virtual":false,"bundle_layout":"","bundle_add_to_cart_form_location":"","bundle_editable_in_cart":false,"bundle_sold_individually_context":"","bundle_item_grouping":"","bundle_min_size":"","bundle_max_size":"","bundle_price":[],"bundled_items":[],"bundle_sell_ids":[],"group_of_quantity":0,"min_quantity":0,"max_quantity":"","exclude_order_quantity_value_rules":"no","exclude_category_quantity_rules":"no","combine_variations":"no","exclude_global_add_ons":[],"addons":[],"permalink_manager":null,"_links":{"self":[{"href":"https:\/\/enertik.com\/mx\/wp-json\/wp\/v2\/product\/30815","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/enertik.com\/mx\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/enertik.com\/mx\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/enertik.com\/mx\/wp-json\/wp\/v2\/comments?post=30815"}],"version-history":[{"count":0,"href":"https:\/\/enertik.com\/mx\/wp-json\/wp\/v2\/product\/30815\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/enertik.com\/mx\/wp-json\/wp\/v2\/media\/30818"}],"wp:attachment":[{"href":"https:\/\/enertik.com\/mx\/wp-json\/wp\/v2\/media?parent=30815"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/enertik.com\/mx\/wp-json\/wp\/v2\/product_brand?post=30815"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/enertik.com\/mx\/wp-json\/wp\/v2\/product_cat?post=30815"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/enertik.com\/mx\/wp-json\/wp\/v2\/product_tag?post=30815"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}