{"id":10952,"date":"2023-02-21T11:11:00","date_gmt":"2023-02-21T14:11:00","guid":{"rendered":"https:\/\/test.enertik.com\/ar\/?post_type=product&#038;p=10952"},"modified":"2026-09-01T18:33:19","modified_gmt":"2026-09-01T21:33:19","slug":"tanque-de-repuesto-para-termo-solar-galvanizado-200l","status":"publish","type":"product","link":"https:\/\/enertik.com\/ar\/tienda\/solar-termica\/accesorios-de-energia-termica\/atmosfericos\/tanque-para-termo-solar-atmosferico-galvanizado-200l\/","title":{"rendered":"Tanque para Termo Solar Atmosf\u00e9rico \u2013 Galvanizado 200L"},"content":{"rendered":"\t\t<div data-elementor-type=\"product-post\" data-elementor-id=\"10952\" class=\"elementor elementor-10952\" data-elementor-post-type=\"product\">\n\t\t\t\t\t\t<section class=\"wd-negative-gap elementor-section elementor-top-section elementor-element elementor-element-fdcf9a0 Product_Description elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fdcf9a0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b188e91\" data-id=\"b188e91\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"wd-negative-gap elementor-section elementor-inner-section elementor-element elementor-element-3a9676e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3a9676e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-e3138ad\" data-id=\"e3138ad\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4f45a32 elementor-widget elementor-widget-wd_tabs\" data-id=\"4f45a32\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"wd-tabs tabs-design-default\">\n\t\t\t<div class=\"wd-tabs-header text-center\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"wd-nav-wrapper wd-nav-tabs-wrapper wd-mb-action-swipe color-scheme-light\">\n\t\t\t\t\t<ul class=\"wd-nav wd-nav-tabs wd-icon-pos-left wd-style-underline\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t<a href=\"#\" class=\"wd-nav-link\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<span class=\"nav-link-text wd-tabs-title\">\n\t\t\t\t\t\t\t\t\t\tESPECIFICACIONES\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/li>\n\n\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t<div class=\"wd-tabs-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"wd-tab-content wd-entry-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div >\n\t\t\t\t\t\t\t\t<table><tbody><tr class=\"tbBorderNone\"><td class=\"tbLeft\">Modelo<\/td><td colspan=\"3\">SW-200T<\/td><\/tr><tr><td class=\"tbTit\" colspan=\"4\">Especificaciones generales<\/td><\/tr><tr><td class=\"tbLeft\">Tipo<\/td><td colspan=\"3\">Termotanque<\/td><\/tr><tr><td class=\"tbLeft\">Sistema<\/td><td colspan=\"3\">Atmosf\u00e9rico<\/td><\/tr><tr><td class=\"tbLeft\">Presi\u00f3n m\u00e1xima de trabajo<\/td><td colspan=\"3\">1 bar<\/td><\/tr><tr><td class=\"tbLeft\">Cantidad de usuarios \/ personas<\/td><td colspan=\"3\">4 ~ 6<\/td><\/tr><tr><td class=\"tbLeft\">Torque de ajuste de conexiones<\/td><td colspan=\"3\">25 newton metro<\/td><\/tr><tr class=\"tbBorderNone\"><td class=\"tbLeft\">Vida \u00fatil m\u00e1xima<\/td><td colspan=\"3\">M\u00e1s de 15 a\u00f1os<\/td><\/tr><tr><td class=\"tbTit\" colspan=\"4\">Especificaciones del tanque<\/td><\/tr><tr><td class=\"tbLeft\">Capacidad del tanque<\/td><td colspan=\"3\">200<\/td><\/tr><tr><td class=\"tbLeft\">Material tanque interno \/ espesor (mm)<\/td><td colspan=\"3\">Acero Inoxidable SUS304-2B \/ 0.51<\/td><\/tr><tr><td class=\"tbLeft\">Material tanque externo \/ espesor (mm)<\/td><td colspan=\"3\">Acero Galvanizado \/ 0.4<\/td><\/tr><tr><td class=\"tbLeft\">Di\u00e1metro tanque interno \/ externo (mm)<\/td><td colspan=\"3\">360 \/ 460<\/td><\/tr><tr class=\"tbBorderNone\"><td class=\"tbLeft\">Aislamiento t\u00e9rmico \/ espesor (mm)<\/td><td colspan=\"3\">Espuma de poliuretano de alta densidad \/ 50<\/td><\/tr><tr><td class=\"tbTit\" colspan=\"4\">Especificaciones de temperatura<\/td><\/tr><tr><td class=\"tbLeft\">Temperatura promedio en verano<\/td><td colspan=\"3\">70\u00baC ~ 85\u00baC<\/td><\/tr><tr><td class=\"tbLeft\">Temperatura promedio en invierno<\/td><td colspan=\"3\">45\u00baC ~ 55\u00baC<\/td><\/tr><tr><td class=\"tbLeft\">Temperatura promedio inicial (verano)<\/td><td colspan=\"3\">\u2264 65\u00baC a los 90 min<\/td><\/tr><tr class=\"tbBorderNone\"><td class=\"tbLeft\">Preservaci\u00f3n del calor en tanque<\/td><td colspan=\"3\">60 ~ 72h<\/td><\/tr><tr><td class=\"tbTit\" colspan=\"4\">Especificaciones del embalaje<\/td><\/tr><tr><td class=\"tbLeft\">\u00a0<\/td><td>Cantidad de bultos<\/td><td>Dimensiones (mm)<\/td><td>Peso neto (kg)<\/td><\/tr><tr><td class=\"tbLeft\">Tanque<\/td><td>1<\/td><td>1710 x 490 x 500<\/td><td>23<\/td><\/tr><\/tbody><\/table>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Tanque de repuesto para modelo SW-200. Cantidad de usuarios: 4~6. Tanque interno de acero inoxidable 304. Espuma de poliuretano de alta densidad como aislante. Tubos de cristal borosilicato de alta calidad. Temperatura promedio en invierno 45\u00baC ~ 55\u00baC. Preservaci\u00f3n del calor en tanque durante 60 ~ 72h. Vida \u00fatil m\u00e1xima: 15 a\u00f1os.<\/p>\n","protected":false},"featured_media":9174,"comment_status":"open","ping_status":"closed","template":"","meta":{"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","inline_featured_image":false,"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":""},"product_brand":[5417],"product_cat":[1711,1712,1709],"product_tag":[],"class_list":["post-10952","product","type-product","status-publish","has-post-thumbnail","product_brand-enertik","product_cat-accesorios-de-energia-termica","product_cat-atmosfericos","product_cat-termotanques-solares-atmosfericos","pa_gtin-3943","pa_litros-200l","pa_material-acero-galvanizado","pa_mpn-sw-200t","pa_mpn-sw-200tmp","pa_mpn-sw-200tsm","first","instock","sale","taxable","shipping-taxable","purchasable","product-type-variable","has-default-attributes"],"bundled_by":[],"bundle_stock_status":"instock","bundle_stock_quantity":null,"bundle_virtual":false,"bundle_layout":"","bundle_add_to_cart_form_location":"","bundle_editable_in_cart":false,"bundle_sold_individually_context":"","bundle_item_grouping":"","bundle_min_size":"","bundle_max_size":"","bundle_price":[],"bundled_items":[],"bundle_sell_ids":[],"group_of_quantity":0,"min_quantity":0,"max_quantity":"","exclude_order_quantity_value_rules":"no","exclude_category_quantity_rules":"no","combine_variations":"no","exclude_global_add_ons":[],"addons":[],"permalink_manager":null,"_links":{"self":[{"href":"https:\/\/enertik.com\/ar\/wp-json\/wp\/v2\/product\/10952","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/enertik.com\/ar\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/enertik.com\/ar\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/enertik.com\/ar\/wp-json\/wp\/v2\/comments?post=10952"}],"version-history":[{"count":0,"href":"https:\/\/enertik.com\/ar\/wp-json\/wp\/v2\/product\/10952\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/enertik.com\/ar\/wp-json\/wp\/v2\/media\/9174"}],"wp:attachment":[{"href":"https:\/\/enertik.com\/ar\/wp-json\/wp\/v2\/media?parent=10952"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/enertik.com\/ar\/wp-json\/wp\/v2\/product_brand?post=10952"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/enertik.com\/ar\/wp-json\/wp\/v2\/product_cat?post=10952"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/enertik.com\/ar\/wp-json\/wp\/v2\/product_tag?post=10952"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}