{"id":10656,"date":"2023-02-21T11:09:17","date_gmt":"2023-02-21T14:09:17","guid":{"rendered":"https:\/\/test.enertik.com\/ar\/?post_type=product&#038;p=10656"},"modified":"2026-09-01T18:30:02","modified_gmt":"2026-09-01T21:30:02","slug":"inversor-y-cargador-de-baterias-mppt-5600w-48vcc","status":"publish","type":"product","link":"https:\/\/enertik.com\/ar\/tienda\/inversores\/inversores-cargadores\/con-regulador-solar-mppt\/inversor-y-cargador-de-baterias-mppt-5600w-48vcc\/","title":{"rendered":"Inversor y Cargador de Bater\u00edas MPPT \u2013 5600W 48Vcc"},"content":{"rendered":"\t\t<div data-elementor-type=\"product-post\" data-elementor-id=\"10656\" class=\"elementor elementor-10656\" data-elementor-post-type=\"product\">\n\t\t\t\t\t\t<section class=\"wd-negative-gap elementor-section elementor-top-section elementor-element elementor-element-24a17d9 Product_Description elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"24a17d9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4326738\" data-id=\"4326738\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"wd-negative-gap elementor-section elementor-inner-section elementor-element elementor-element-f7beed2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f7beed2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-c57e7ee\" data-id=\"c57e7ee\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ad220b3 elementor-widget elementor-widget-wd_tabs\" data-id=\"ad220b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"wd-tabs tabs-design-default\">\n\t\t\t<div class=\"wd-tabs-header text-center\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"wd-nav-wrapper wd-nav-tabs-wrapper wd-mb-action-swipe color-scheme-light\">\n\t\t\t\t\t<ul class=\"wd-nav wd-nav-tabs wd-icon-pos-left wd-style-underline\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t<a href=\"#\" class=\"wd-nav-link\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<span class=\"nav-link-text wd-tabs-title\">\n\t\t\t\t\t\t\t\t\t\tDESCRIPCI\u00d3N\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/li>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t<a href=\"#\" class=\"wd-nav-link\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<span class=\"nav-link-text wd-tabs-title\">\n\t\t\t\t\t\t\t\t\t\tESPECIFICACIONES\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/li>\n\n\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t<div class=\"wd-tabs-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"wd-tab-content wd-entry-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div >\n\t\t\t\t\t\t\t\t<h2>VENTAJAS<\/h2><div id=\"1653922194332-e106eafb-4eea8590-8091\" class=\"vc_tta-panel vc_active\" data-vc-content=\".vc_tta-panel-body\"><div class=\"vc_tta-panel-body\"><div class=\"wpb_text_column wpb_content_element vc_custom_1655386521598\"><div class=\"wpb_wrapper\"><ul class=\"ulMiddle\"><li>Regulador solar MPPT de ALTA POTENCIA incorporado<\/li><li class=\"ulBgColor\">AMPLIO RANGO de tensi\u00f3n de entrada de paneles solares<\/li><li>Arranque de grupo electr\u00f3geno (dispone de salida de contactos secos para el arranque de un generador autom\u00e1ticamente)<\/li><li class=\"ulBgColor\">Puerto BMS para el uso de bater\u00edas de litio<\/li><li>Salida senoidal pura<\/li><li class=\"ulBgColor\">Pantalla con color LCD de 4,3\u2033 con botones t\u00e1ctiles<\/li><li>LED anular multicolor RGB personalizable<\/li><li class=\"ulBgColor\">Cargador autom\u00e1tico de 3 etapas<\/li><li>Dise\u00f1o para operaci\u00f3n continua las 24 horas<\/li><li class=\"ulBgColor\">Prioridad seleccionable (red\/grupo, solar o bater\u00edas)<\/li><li>Funci\u00f3n de arranque en fr\u00edo<\/li><li class=\"ulBgColor\">Dise\u00f1o para montaje en pared<\/li><li>Alta eficiencia para ahorrar energ\u00eda<\/li><li class=\"ulBgColor\">Ecualizaci\u00f3n de la bater\u00eda para optimizar el rendimiento y ciclo de vida de la misma<\/li><li>Monitoreo v\u00eda WiFi incorporado (Aplicaci\u00f3n para Android y iOS disponibles desde Play Store y App Store)<\/li><li class=\"ulBgColor\">M\u00f3dulo de monitoreo WiFi<\/li><li>Permite guardar reportes de funcionamiento en pendrive USB<\/li><li class=\"ulBgColor\">Filtro antipolvo incorporado<\/li><\/ul><\/div><\/div><\/div><\/div><div id=\"1655386527977-51c4da1d-d8e2\" class=\"vc_tta-panel\" data-vc-content=\".vc_tta-panel-body\"><div class=\"vc_tta-panel-heading\"><h4 class=\"vc_tta-panel-title vc_tta-controls-icon-position-left\">\u00a0<\/h4><\/div><\/div><h2>PROTECCIONES DEL EQUIPO<\/h2><ul class=\"ulMiddle\"><li>Cortocircuito<\/li><li class=\"ulBgColor\">Sobrecarga<\/li><li>Alta tensi\u00f3n de entrada<\/li><li class=\"ulBgColor\">Baja tensi\u00f3n de entrada<\/li><li>Sobre temperatura<\/li><\/ul>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"wd-tab-content wd-entry-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div >\n\t\t\t\t\t\t\t\t<table><tbody><tr><td class=\"tbLeft\">Modelo<\/td><td colspan=\"2\">ICD-5.6K-48<\/td><\/tr><tr class=\"tbBorderNone\"><td class=\"tbLeft\">Potencia continua<\/td><td colspan=\"2\">5600VA \/ 5600W<\/td><\/tr><tr class=\"tbBorderNone\"><td class=\"tbTit\" colspan=\"3\">Entrada<\/td><\/tr><tr><td class=\"tbLeft\">Voltaje nominal<\/td><td colspan=\"2\">230VCA<\/td><\/tr><tr><td class=\"tbLeft\">Rango de voltaje aceptable<\/td><td colspan=\"2\">90~280VCA<\/td><\/tr><tr><td class=\"tbLeft\">Frecuencia<\/td><td colspan=\"2\">50 \/ 60Hz (reconocimiento autom\u00e1tico)<\/td><\/tr><tr class=\"tbBorderNone\"><td class=\"tbLeft\">Autoconsumo<\/td><td colspan=\"2\">&lt; 40W<\/td><\/tr><tr class=\"tbBorderNone\"><td class=\"tbTit\" colspan=\"3\">Salida<\/td><\/tr><tr><td class=\"tbLeft\">Regulaci\u00f3n de voltaje (modo inversor)<\/td><td colspan=\"2\">230VCA \u00b1 5%<\/td><\/tr><tr><td class=\"tbLeft\">Potencia de pico<\/td><td colspan=\"2\">11200VA<\/td><\/tr><tr><td class=\"tbLeft\">Tiempo de transferencia<\/td><td colspan=\"2\">15ms ~ 20ms<\/td><\/tr><tr class=\"tbBorderNone\"><td class=\"tbLeft\">Forma de onda<\/td><td colspan=\"2\">Senoidal pura<\/td><\/tr><tr class=\"tbBorderNone\"><td class=\"tbTit\" colspan=\"3\">Bater\u00eda<\/td><\/tr><tr><td class=\"tbLeft\">Voltaje de bater\u00eda<\/td><td colspan=\"2\">48VCC<\/td><\/tr><tr><td class=\"tbLeft\">Voltaje flote<\/td><td colspan=\"2\">54VCC<\/td><\/tr><tr class=\"tbBorderNone\"><td class=\"tbLeft\">Protecci\u00f3n de sobrecarga<\/td><td colspan=\"2\">63VCC<\/td><\/tr><tr class=\"tbBorderNone\"><td class=\"tbTit\" colspan=\"3\">Cargador y regulador solar<\/td><\/tr><tr><td class=\"tbLeft\">Tipo<\/td><td colspan=\"2\">MPPT<\/td><\/tr><tr><td class=\"tbLeft\">Potencia m\u00e1xima de panel<\/td><td colspan=\"2\">6000W<\/td><\/tr><tr><td class=\"tbLeft\">Voltaje de entrada MPPT<\/td><td colspan=\"2\">120VCC ~ 450VCC<\/td><\/tr><tr><td class=\"tbLeft\">Voltaje de entrada nominal (m\u00ednimo) desde paneles<\/td><td colspan=\"2\">360VCC<\/td><\/tr><tr><td class=\"tbLeft\">Voltaje de entrada m\u00e1ximo desde paneles<\/td><td colspan=\"2\">500VCC<\/td><\/tr><tr><td class=\"tbLeft\">Corriente de entrada m\u00e1xima desde paneles<\/td><td colspan=\"2\">18A<\/td><\/tr><tr><td class=\"tbLeft\">Corriente de carga m\u00e1xima \u2013 cargador solar<\/td><td colspan=\"2\">120A<\/td><\/tr><tr><td class=\"tbLeft\">Corriente de carga m\u00e1xima \u2013 cargador CA<\/td><td colspan=\"2\">100A<\/td><\/tr><tr><td class=\"tbLeft\">Corriente de carga conjunta m\u00e1xima (solar + CA)<\/td><td colspan=\"2\">120A<\/td><\/tr><tr class=\"tbBorderNone\"><td class=\"tbLeft\">Eficiencia<\/td><td colspan=\"2\">93%<\/td><\/tr><tr><td class=\"tbTit\" colspan=\"3\">Ambiente<\/td><\/tr><tr><td class=\"tbLeft\">Temperatura de operaci\u00f3n<\/td><td colspan=\"2\">-10 ~ 50 \u00b0C<\/td><\/tr><tr class=\"tbBorderNone\"><td class=\"tbLeft\">Humedad relativa<\/td><td colspan=\"2\">5 ~ 95% (sin condensaci\u00f3n)<\/td><\/tr><tr><td class=\"tbTit\" colspan=\"3\">Especificaciones f\u00edsicas<\/td><\/tr><tr><td class=\"tbLeft\">Interfaces de comunicaci\u00f3n<\/td><td colspan=\"2\">USB \/ RS232 \/ RS485 \/ WiFi \/ Dry-contact<\/td><\/tr><tr><td class=\"tbLeft\">Dimensiones (mm)<\/td><td colspan=\"2\">119 x 313.6 x 422.8<\/td><\/tr><tr><td class=\"tbLeft\">Peso neto (kg)<\/td><td colspan=\"2\">12<\/td><\/tr><\/tbody><\/table>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"wd-negative-gap elementor-section elementor-top-section elementor-element elementor-element-79fc8e0 Link_Buttons elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"79fc8e0\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-custom\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-caea4ac\" data-id=\"caea4ac\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b23d620 elementor-view-framed elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"b23d620\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/enertik.com\/wp-content\/uploads\/sites\/2\/documentos\/manuales\/manual-inversor-cargador-solar-icd-36k-24-icd-56k-48.pdf\" target=\"_blank\" class=\"elementor-icon\" tabindex=\"-1\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-book\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M448 360V24c0-13.3-10.7-24-24-24H96C43 0 0 43 0 96v320c0 53 43 96 96 96h328c13.3 0 24-10.7 24-24v-16c0-7.5-3.5-14.3-8.9-18.7-4.2-15.4-4.2-59.3 0-74.7 5.4-4.3 8.9-11.1 8.9-18.6zM128 134c0-3.3 2.7-6 6-6h212c3.3 0 6 2.7 6 6v20c0 3.3-2.7 6-6 6H134c-3.3 0-6-2.7-6-6v-20zm0 64c0-3.3 2.7-6 6-6h212c3.3 0 6 2.7 6 6v20c0 3.3-2.7 6-6 6H134c-3.3 0-6-2.7-6-6v-20zm253.4 250H96c-17.7 0-32-14.3-32-32 0-17.6 14.4-32 32-32h285.4c-1.9 17.1-1.9 46.9 0 64z\"><\/path><\/svg>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tMANUAL\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-63317a3\" data-id=\"63317a3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aee6e4f elementor-view-framed elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"aee6e4f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/play.google.com\/store\/apps\/details?id=com.eybond.smartclient.energymate\" target=\"_blank\" class=\"elementor-icon\" tabindex=\"-1\" rel=\"noopener\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-google-play\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M325.3 234.3L104.6 13l280.8 161.2-60.1 60.1zM47 0C34 6.8 25.3 19.2 25.3 35.3v441.3c0 16.1 8.7 28.5 21.7 35.3l256.6-256L47 0zm425.2 225.6l-58.9-34.1-65.7 64.5 65.7 64.5 60.1-34.1c18-14.3 18-46.5-1.2-60.8zM104.6 499l280.8-161.2-60.1-60.1L104.6 499z\"><\/path><\/svg>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tAPP ANDROID\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-f90d9c6\" data-id=\"f90d9c6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9479c78 elementor-view-framed elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"9479c78\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/apps.apple.com\/app\/energy-mate\/id1672569936\" target=\"_blank\" class=\"elementor-icon\" tabindex=\"-1\" rel=\"noopener\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-app-store-ios\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M400 32H48C21.5 32 0 53.5 0 80v352c0 26.5 21.5 48 48 48h352c26.5 0 48-21.5 48-48V80c0-26.5-21.5-48-48-48zM127 384.5c-5.5 9.6-17.8 12.8-27.3 7.3-9.6-5.5-12.8-17.8-7.3-27.3l14.3-24.7c16.1-4.9 29.3-1.1 39.6 11.4L127 384.5zm138.9-53.9H84c-11 0-20-9-20-20s9-20 20-20h51l65.4-113.2-20.5-35.4c-5.5-9.6-2.2-21.8 7.3-27.3 9.6-5.5 21.8-2.2 27.3 7.3l8.9 15.4 8.9-15.4c5.5-9.6 17.8-12.8 27.3-7.3 9.6 5.5 12.8 17.8 7.3 27.3l-85.8 148.6h62.1c20.2 0 31.5 23.7 22.7 40zm98.1 0h-29l19.6 33.9c5.5 9.6 2.2 21.8-7.3 27.3-9.6 5.5-21.8 2.2-27.3-7.3-32.9-56.9-57.5-99.7-74-128.1-16.7-29-4.8-58 7.1-67.8 13.1 22.7 32.7 56.7 58.9 102h52c11 0 20 9 20 20 0 11.1-9 20-20 20z\"><\/path><\/svg>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tAPP IOS\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-d0d6813\" data-id=\"d0d6813\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-325b190 elementor-view-framed elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"325b190\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/enertik.com\/wp-content\/uploads\/sites\/2\/documentos\/manuales\/energy-mate-app-user-manual-20230628.pdf\" target=\"_blank\" class=\"elementor-icon\" tabindex=\"-1\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-book\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M448 360V24c0-13.3-10.7-24-24-24H96C43 0 0 43 0 96v320c0 53 43 96 96 96h328c13.3 0 24-10.7 24-24v-16c0-7.5-3.5-14.3-8.9-18.7-4.2-15.4-4.2-59.3 0-74.7 5.4-4.3 8.9-11.1 8.9-18.6zM128 134c0-3.3 2.7-6 6-6h212c3.3 0 6 2.7 6 6v20c0 3.3-2.7 6-6 6H134c-3.3 0-6-2.7-6-6v-20zm0 64c0-3.3 2.7-6 6-6h212c3.3 0 6 2.7 6 6v20c0 3.3-2.7 6-6 6H134c-3.3 0-6-2.7-6-6v-20zm253.4 250H96c-17.7 0-32-14.3-32-32 0-17.6 14.4-32 32-32h285.4c-1.9 17.1-1.9 46.9 0 64z\"><\/path><\/svg>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tMANAUL DE LA APP\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Inversor Senoidal 48v \u2013 220v 5600VA, Regulador Solar MPPT Rango Amplio 120A. Monitoreo v\u00eda WiFi incorporado, Pantalla con color LCD 4,3\u2033 con botones t\u00e1ctiles<\/p>\n","protected":false},"featured_media":9086,"comment_status":"open","ping_status":"closed","template":"","meta":{"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","inline_featured_image":false,"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":""},"product_brand":[5417],"product_cat":[1725,1723],"product_tag":[1958],"class_list":["post-10656","product","type-product","status-publish","has-post-thumbnail","product_brand-enertik","product_cat-con-regulador-solar-mppt","product_cat-inversores-cargadores","product_tag-nuevos","pa_mpn-icd-5-6k-48","pa_potencia-5600w","pa_serie-serie-ivmq","pa_voltaje-48v","first","instock","sale","taxable","shipping-taxable","purchasable","product-type-simple"],"bundled_by":[],"bundle_stock_status":"instock","bundle_stock_quantity":2,"bundle_virtual":false,"bundle_layout":"","bundle_add_to_cart_form_location":"","bundle_editable_in_cart":false,"bundle_sold_individually_context":"","bundle_item_grouping":"","bundle_min_size":"","bundle_max_size":"","bundle_price":[],"bundled_items":[],"bundle_sell_ids":[],"group_of_quantity":0,"min_quantity":0,"max_quantity":"","exclude_order_quantity_value_rules":"no","exclude_category_quantity_rules":"no","combine_variations":"no","exclude_global_add_ons":[],"addons":[],"permalink_manager":null,"_links":{"self":[{"href":"https:\/\/enertik.com\/ar\/wp-json\/wp\/v2\/product\/10656","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/enertik.com\/ar\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/enertik.com\/ar\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/enertik.com\/ar\/wp-json\/wp\/v2\/comments?post=10656"}],"version-history":[{"count":0,"href":"https:\/\/enertik.com\/ar\/wp-json\/wp\/v2\/product\/10656\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/enertik.com\/ar\/wp-json\/wp\/v2\/media\/9086"}],"wp:attachment":[{"href":"https:\/\/enertik.com\/ar\/wp-json\/wp\/v2\/media?parent=10656"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/enertik.com\/ar\/wp-json\/wp\/v2\/product_brand?post=10656"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/enertik.com\/ar\/wp-json\/wp\/v2\/product_cat?post=10656"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/enertik.com\/ar\/wp-json\/wp\/v2\/product_tag?post=10656"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}